{"id":672,"count":1,"description":"","link":"https:\/\/zimdailyjournal.co.zw\/index.php\/tag\/abas-amidu\/","name":"Abas Amidu","slug":"abas-amidu","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abas Amidu Archives - zimdailyjournal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zimdailyjournal.co.zw\/index.php\/tag\/abas-amidu\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abas Amidu Archives - zimdailyjournal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zimdailyjournal.co.zw\/index.php\/tag\/abas-amidu\/\" \/>\n<meta property=\"og:site_name\" content=\"zimdailyjournal\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zimdailyjournal.co.zw\/wp-content\/uploads\/2025\/09\/Screenshot-2025-09-16-082828.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1389\" \/>\n\t<meta property=\"og:image:height\" content=\"837\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/zimdailyjournal.co.zw\\\/index.php\\\/tag\\\/abas-amidu\\\/\",\"url\":\"https:\\\/\\\/zimdailyjournal.co.zw\\\/index.php\\\/tag\\\/abas-amidu\\\/\",\"name\":\"Abas Amidu Archives - zimdailyjournal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zimdailyjournal.co.zw\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zimdailyjournal.co.zw\\\/index.php\\\/tag\\\/abas-amidu\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zimdailyjournal.co.zw\\\/index.php\\\/tag\\\/abas-amidu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/zimdailyjournal.co.zw\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abas Amidu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zimdailyjournal.co.zw\\\/#website\",\"url\":\"https:\\\/\\\/zimdailyjournal.co.zw\\\/\",\"name\":\"zimdailyjournal\",\"description\":\"Everytime news you can trust\",\"publisher\":{\"@id\":\"https:\\\/\\\/zimdailyjournal.co.zw\\\/#organization\"},\"alternateName\":\"Zimbabwe Daily Journal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zimdailyjournal.co.zw\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zimdailyjournal.co.zw\\\/#organization\",\"name\":\"Zimdaily Journal\",\"alternateName\":\"Zimdaily Journal\",\"url\":\"https:\\\/\\\/zimdailyjournal.co.zw\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zimdailyjournal.co.zw\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zimdailyjournal.co.zw\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Zimdaily-journal-03.jpg\",\"contentUrl\":\"https:\\\/\\\/zimdailyjournal.co.zw\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Zimdaily-journal-03.jpg\",\"width\":2268,\"height\":751,\"caption\":\"Zimdaily Journal\"},\"image\":{\"@id\":\"https:\\\/\\\/zimdailyjournal.co.zw\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ZimDailyJournal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abas Amidu Archives - zimdailyjournal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zimdailyjournal.co.zw\/index.php\/tag\/abas-amidu\/","og_locale":"en_US","og_type":"article","og_title":"Abas Amidu Archives - zimdailyjournal","og_url":"https:\/\/zimdailyjournal.co.zw\/index.php\/tag\/abas-amidu\/","og_site_name":"zimdailyjournal","og_image":[{"width":1389,"height":837,"url":"https:\/\/zimdailyjournal.co.zw\/wp-content\/uploads\/2025\/09\/Screenshot-2025-09-16-082828.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/zimdailyjournal.co.zw\/index.php\/tag\/abas-amidu\/","url":"https:\/\/zimdailyjournal.co.zw\/index.php\/tag\/abas-amidu\/","name":"Abas Amidu Archives - zimdailyjournal","isPartOf":{"@id":"https:\/\/zimdailyjournal.co.zw\/#website"},"breadcrumb":{"@id":"https:\/\/zimdailyjournal.co.zw\/index.php\/tag\/abas-amidu\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/zimdailyjournal.co.zw\/index.php\/tag\/abas-amidu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/zimdailyjournal.co.zw\/"},{"@type":"ListItem","position":2,"name":"Abas Amidu"}]},{"@type":"WebSite","@id":"https:\/\/zimdailyjournal.co.zw\/#website","url":"https:\/\/zimdailyjournal.co.zw\/","name":"zimdailyjournal","description":"Everytime news you can trust","publisher":{"@id":"https:\/\/zimdailyjournal.co.zw\/#organization"},"alternateName":"Zimbabwe Daily Journal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zimdailyjournal.co.zw\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/zimdailyjournal.co.zw\/#organization","name":"Zimdaily Journal","alternateName":"Zimdaily Journal","url":"https:\/\/zimdailyjournal.co.zw\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zimdailyjournal.co.zw\/#\/schema\/logo\/image\/","url":"https:\/\/zimdailyjournal.co.zw\/wp-content\/uploads\/2024\/01\/Zimdaily-journal-03.jpg","contentUrl":"https:\/\/zimdailyjournal.co.zw\/wp-content\/uploads\/2024\/01\/Zimdaily-journal-03.jpg","width":2268,"height":751,"caption":"Zimdaily Journal"},"image":{"@id":"https:\/\/zimdailyjournal.co.zw\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ZimDailyJournal"]}]}},"_links":{"self":[{"href":"https:\/\/zimdailyjournal.co.zw\/index.php\/wp-json\/wp\/v2\/tags\/672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zimdailyjournal.co.zw\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/zimdailyjournal.co.zw\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/zimdailyjournal.co.zw\/index.php\/wp-json\/wp\/v2\/posts?tags=672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}